{"id":1302,"date":"2019-09-10T12:00:38","date_gmt":"2019-09-10T10:00:38","guid":{"rendered":"http:\/\/chsspaca.fr\/?p=1302"},"modified":"2019-09-10T12:00:38","modified_gmt":"2019-09-10T10:00:38","slug":"diplome-de-temoignage-de-satisfaction-de-sauvetage","status":"publish","type":"post","link":"https:\/\/chsspaca.fr\/index.php\/2019\/09\/10\/diplome-de-temoignage-de-satisfaction-de-sauvetage\/","title":{"rendered":"Dipl\u00f4me de t\u00e9moignage de satisfaction de sauvetage"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<strong><b>Dipl\u00f4me de t\u00e9moignage de satisfaction de sauvetage<\/b>, Marseille, 1912<\/strong><\/p>\n<p><strong>Collection priv\u00e9e<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong>C\u2019est le Second Empire qui organise la rationalisation des secours aux naufrages<a href=\"applewebdata:\/\/E4EB929D-CE8F-450D-84DE-E93DBDBE08F4#_ftn1\" name=\"_ftnref1\">[1]<\/a>d\u2019abord sur les c\u00f4tes septentrionales puis m\u00e9ridionales car comme un de nos num\u00e9ros th\u00e9matiquesl\u2019a montr\u00e9 en 2015, la \u00ab\u00a0<em>M\u00e9diterran\u00e9e peut \u00eatre un mer dangereuse\u00a0<\/em>\u00bb. Aussi en 1865, est fond\u00e9e sous patronage officiel du pouvoir politique une soci\u00e9t\u00e9 priv\u00e9e <strong><em>la Soci\u00e9t\u00e9 Centrale de Sauvetage des Naufrag\u00e9s<\/em><\/strong>. Elle vient en aide aux victimes d\u2019une avarie mais aussi aux sauveteurs qui disparaissent lors de leurs actes de courage comme nous l\u2019a rappel\u00e9 une triste actualit\u00e9\u00a0 en Vend\u00e9e avec le chavirement au d\u00e9but du mois de juin dernier d\u2019un canot de sauvetage causant trois disparitions au large des Sables-d\u2019Olonne.<\/p>\n<p>Elle aide ainsi les familles des sauveteurs volontaires b\u00e9n\u00e9voles disparus par de secours \u00a0mat\u00e9riels et moraux et notamment des prises en charge de scolarit\u00e9 des orphelins.<\/p>\n<p>En 1967, la Soci\u00e9t\u00e9 fusionne avec la Soci\u00e9t\u00e9 nationale de sauvetage en mer et avec la <em>Soci\u00e9t\u00e9 des sauveteurs hospitaliers bretons<\/em>pour former l\u2019actuelle <strong><em>Soci\u00e9t\u00e9 nationale de sauvetage en mer.<\/em><\/strong><\/p>\n<p>Ce dipl\u00f4me remis au r\u00e9cipiendaire atteste de la ma\u00eetrise d\u2019un douanier marseillais lors de la r\u00e9animation d\u2019un enfant, il s\u2019accompagnait souvent de l\u2019attribution d\u2019une m\u00e9daille priv\u00e9e portable.<\/p>\n<p><strong><em>Olivier Vernier<\/em><\/strong><\/p>\n<p><a href=\"applewebdata:\/\/E4EB929D-CE8F-450D-84DE-E93DBDBE08F4#_ftnref1\" name=\"_ftn1\">[1]<\/a>\u00a0 Voir Fr\u00e9d\u00e9ric Caille, La figure du sauveteur. Naissance du citoyen secoureur en France, 1780-1914, Presses universitaires de Rennes, 2015.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Dipl\u00f4me de t\u00e9moignage de satisfaction de sauvetage, Marseille, 1912 Collection priv\u00e9e &nbsp; \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 C\u2019est le Second Empire qui organise la rationalisation des secours aux naufrages[1]d\u2019abord sur les c\u00f4tes septentrionales puis m\u00e9ridionales car comme un de nos num\u00e9ros th\u00e9matiquesl\u2019a montr\u00e9 en 2015, la \u00ab\u00a0M\u00e9diterran\u00e9e peut \u00eatre un mer dangereuse\u00a0\u00bb. Aussi en 1865, est fond\u00e9e sous patronage &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/chsspaca.fr\/index.php\/2019\/09\/10\/diplome-de-temoignage-de-satisfaction-de-sauvetage\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Dipl\u00f4me de t\u00e9moignage de satisfaction de sauvetage&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":1304,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2,4],"tags":[],"class_list":["post-1302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoire","category-public"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/posts\/1302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1302"}],"version-history":[{"count":0,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/posts\/1302\/revisions"}],"wp:attachment":[{"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}