{"id":1615,"date":"2021-04-10T11:02:00","date_gmt":"2021-04-10T09:02:00","guid":{"rendered":"http:\/\/chsspaca.fr\/?p=1615"},"modified":"2022-06-23T11:00:08","modified_gmt":"2022-06-23T09:00:08","slug":"medaille-commemorative-du-trentieme-anniversaire-de-la-creation-du-reseau-des-caisses-de-conges-payes-des-secteurs-du-batiment-et-des-travaux-publics","status":"publish","type":"post","link":"https:\/\/chsspaca.fr\/index.php\/2021\/04\/10\/medaille-commemorative-du-trentieme-anniversaire-de-la-creation-du-reseau-des-caisses-de-conges-payes-des-secteurs-du-batiment-et-des-travaux-publics\/","title":{"rendered":"M\u00e9daille comm\u00e9morative du trenti\u00e8me anniversaire de la cr\u00e9ation du r\u00e9seau des caisses de cong\u00e9s pay\u00e9s des secteurs du b\u00e2timent et des travaux publics"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A la suite de la victoire du Front populaire, un droit social nouveau est \u00e9labor\u00e9. Les cong\u00e9s pay\u00e9s sont n\u00e9goci\u00e9s le&nbsp;7 juin 1936&nbsp;par la signature des accords de Matignon entre le nouveau Pr\u00e9sident du conseil, L\u00e9on Blum, la Conf\u00e9d\u00e9ration g\u00e9n\u00e9rale du patronat fran\u00e7ais et la Conf\u00e9d\u00e9ration g\u00e9n\u00e9rale du travail. Le&nbsp;<em>Journal Officiel<\/em>&nbsp;du 20 juin 1936 publie la loi instituant 15 jours de cong\u00e9s pay\u00e9s annuels<a href=\"applewebdata:\/\/E7665C54-059B-44ED-9B20-23ACC29B4A94#_ftn1\"><sup>[1]<\/sup><\/a>&nbsp;(et la semaine de 40 heures). Cette ann\u00e9e-l\u00e0, 600 000 personnes partent en vacances. L\u00e9o Lagrange, sous-secr\u00e9taire d\u2019Etat&nbsp;aux Sports et \u00e0 l&#8217;Organisation des loisirs aupr\u00e8s du ministre de la Sant\u00e9 publique, n\u00e9gocie un billet populaire de chemin de fer cong\u00e9s annuel \u00e0 tarif r\u00e9duit dont 907 000 personnes b\u00e9n\u00e9ficient en 1937.&nbsp;Cette m\u00eame loi pr\u00e9voyait la constitution de caisses de compensation entre les employeurs dans certaines professions d\u00e9sign\u00e9es par d\u00e9cret&nbsp;dont le puissant secteur du b\u00e2timent et des travaux publics qui r\u00e9unit des entreprises tr\u00e8s diff\u00e9rentes \u00e0 effectif variable en fonction des chantiers et des saisons. Aussi les bases du r\u00e9gime sp\u00e9cial des cong\u00e9s pay\u00e9s dans le b\u00e2timent et les travaux publics sont&nbsp;fix\u00e9es par le d\u00e9cret du 18 janvier 1937 et l\u2019arr\u00eat\u00e9 du 8 mars 1937. Les&nbsp;caisses du r\u00e9seau national et la caisse de surcompensation sont cr\u00e9\u00e9es entre 1937 et 1947, elles g\u00e8rent le ch\u00f4mage-intemp\u00e9ries et les cong\u00e9s pay\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Pour c\u00e9l\u00e9brer le trentenaire de leur cr\u00e9ation, le r\u00e9seau des caisses de BTP fait appel \u00e0 une&nbsp;sculptrice et m\u00e9dailleuse&nbsp;&nbsp;moderne, rouennaise, sp\u00e9cialis\u00e9e dans les \u00abm\u00e9dailles sociales\u00bb dont la m\u00e9daille officielle d\u2019anciennet\u00e9 frapp\u00e9e sous l\u2019\u00e9gide du minist\u00e8re du Travail, pour la Caisse nationale de pr\u00e9voyance (1975) pour r\u00e9compenser les salari\u00e9-e-s. A l\u2019avers est repr\u00e9sent\u00e9e une sc\u00e8ne de chantiers de construction assur\u00e9ment tr\u00e8s contemporaine mais au revers trois jeunes gens salari\u00e9s d\u00e9couvrent, comme trente ans auparavant&nbsp;&nbsp;leurs pr\u00e9d\u00e9cesseurs des paysages de montagne et des paysages maritimes \u00ab&nbsp;intemporels&nbsp;\u00bb qui \u00e9voquent nos montagnes (Hautes-Alpes, Alpes-Maritimes) et nos littoraux bas rhodaniens, varois et alpins-maritimiens<a href=\"applewebdata:\/\/E7665C54-059B-44ED-9B20-23ACC29B4A94#_ftn2\"><sup>[2]<\/sup><\/a>&nbsp;contempl\u00e9s pour la premi\u00e8re fois par les salari\u00e9s en cong\u00e9s en 1936.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;L\u2019ann\u00e9e suivante la crise sociale du mois de mai 1968 cristallisera les revendications face \u00e0 une&nbsp;&nbsp;soci\u00e9t\u00e9 que d&#8217;aucuns consid\u00e9reront comme \u00abfig\u00e9\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Olivier Vernier<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"applewebdata:\/\/E7665C54-059B-44ED-9B20-23ACC29B4A94#_ftnref1\"><sup>[1]<\/sup><\/a>&nbsp;Andr\u00e9 Hut (dir.),&nbsp;<em>Cong\u00e9s pay\u00e9s 36&nbsp;:&nbsp;<\/em><em>histoire<\/em><em>&nbsp;et id\u00e9ologies : actes du colloque organis\u00e9 \u00e0 Bruxelles le 29 novembre 1986 par le mouvement Culture-Tourisme-Loisirs, CTL<\/em>, Bruxelles, Reflet, 1991, 126 p.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"applewebdata:\/\/E7665C54-059B-44ED-9B20-23ACC29B4A94#_ftnref2\"><sup>[2]<\/sup><\/a>&nbsp;Analys\u00e9s de mani\u00e8re cynique et anticip\u00e9e par le cin\u00e9aste Jean Vigo,&nbsp;<em>A propos de Nice&nbsp;<\/em>(1929).<\/p>\n\n\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" data-id=\"1625\" src=\"https:\/\/i0.wp.com\/chsspaca.fr\/wp-content\/uploads\/2021\/02\/30CCPBTP-revers-scaled-e1612809033266.jpg?w=525\" alt=\"\" class=\"wp-image-1625\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" decoding=\"async\" data-id=\"1613\" src=\"https:\/\/i0.wp.com\/chsspaca.fr\/wp-content\/uploads\/2021\/02\/30CCPBTP-avers-scaled-e1612803534125.jpg?w=525\" alt=\"\" class=\"wp-image-1613\"\/><\/figure>\n<figcaption class=\"blocks-gallery-caption\">Josette H\u00e9bert-Co\u00ebffin (1906-1973), M\u00e9daille comm\u00e9morative du trenti\u00e8me anniversaire de la cr\u00e9ation du r\u00e9seau des caisses de cong\u00e9s pay\u00e9s des secteurs du b\u00e2timent et des travaux publics, bronze, offerte par la caisse de Marseille, 1967, collection priv\u00e9e. Clich\u00e9 O.Vernier<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>A la suite de la victoire du Front populaire, un droit social nouveau est \u00e9labor\u00e9. Les cong\u00e9s pay\u00e9s sont n\u00e9goci\u00e9s le&nbsp;7 juin 1936&nbsp;par la signature des accords de Matignon entre le nouveau Pr\u00e9sident du conseil, L\u00e9on Blum, la Conf\u00e9d\u00e9ration g\u00e9n\u00e9rale du patronat fran\u00e7ais et la Conf\u00e9d\u00e9ration g\u00e9n\u00e9rale du travail. Le&nbsp;Journal Officiel&nbsp;du 20 juin 1936 publie &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/chsspaca.fr\/index.php\/2021\/04\/10\/medaille-commemorative-du-trentieme-anniversaire-de-la-creation-du-reseau-des-caisses-de-conges-payes-des-secteurs-du-batiment-et-des-travaux-publics\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;M\u00e9daille comm\u00e9morative du trenti\u00e8me anniversaire de la cr\u00e9ation du r\u00e9seau des caisses de cong\u00e9s pay\u00e9s des secteurs du b\u00e2timent et des travaux publics&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":2452,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[2,4],"tags":[],"class_list":["post-1615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-histoire","category-public"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/chsspaca.fr\/wp-content\/uploads\/2021\/02\/30CCPBTP-revers-scaled.jpg?fit=2560%2C2466&ssl=1","_links":{"self":[{"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/posts\/1615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1615"}],"version-history":[{"count":0,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/posts\/1615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/media\/2452"}],"wp:attachment":[{"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}