{"id":1645,"date":"2021-02-12T07:43:00","date_gmt":"2021-02-12T06:43:00","guid":{"rendered":"http:\/\/chsspaca.fr\/?p=1645"},"modified":"2022-06-23T11:03:25","modified_gmt":"2022-06-23T09:03:25","slug":"le-prix-2021-du-comite-dhistoire-de-la-securite-sociale","status":"publish","type":"post","link":"https:\/\/chsspaca.fr\/index.php\/2021\/02\/12\/le-prix-2021-du-comite-dhistoire-de-la-securite-sociale\/","title":{"rendered":"Le prix 2021 du Comit\u00e9 d&#8217;histoire de la S\u00e9curit\u00e9 sociale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Cette ann\u00e9e encore, le CHSS attribuera&nbsp;\u00e0 l\u2019automne&nbsp;des prix \u00e0 des th\u00e8ses et m\u00e9moires de master sur la protection sociale. La date de d\u00e9p\u00f4t des dossiers de candidatures est fix\u00e9e au&nbsp;<strong>20 mai 2021<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La promotion des prix, en raison des conditions actuelles, sera un peu particuli\u00e8re puisque les universit\u00e9s et leurs biblioth\u00e8ques sont peu fr\u00e9quent\u00e9es, sinon ferm\u00e9es. Nous diffuserons, comme d\u2019habitude, l\u2019information par voie d\u2019affiche mais tous ceux qui pourront nous aider \u00e0 la diffuser&nbsp;dans des r\u00e9seaux&nbsp;d\u2019\u00e9tudiants et d\u2019enseignants-chercheurs seront les bienvenus.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour toute information:<br><strong>Comit\u00e9 d\u2019histoire de la S\u00e9curit\u00e9 sociale<br><a rel=\"noreferrer noopener\" href=\"mailto:chss@sante.gouv.fr\" target=\"_blank\">chss@sante.gouv.fr<\/a><br>14 avenue Duquesne 75350 Paris 07SP<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette ann\u00e9e encore, le CHSS attribuera&nbsp;\u00e0 l\u2019automne&nbsp;des prix \u00e0 des th\u00e8ses et m\u00e9moires de master sur la protection sociale. La date de d\u00e9p\u00f4t des dossiers de candidatures est fix\u00e9e au&nbsp;20 mai 2021. La promotion des prix, en raison des conditions actuelles, sera un peu particuli\u00e8re puisque les universit\u00e9s et leurs biblioth\u00e8ques sont peu fr\u00e9quent\u00e9es, sinon &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/chsspaca.fr\/index.php\/2021\/02\/12\/le-prix-2021-du-comite-dhistoire-de-la-securite-sociale\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Le prix 2021 du Comit\u00e9 d&#8217;histoire de la S\u00e9curit\u00e9 sociale&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":2454,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-1645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-public"],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/chsspaca.fr\/wp-content\/uploads\/2021\/02\/LogoComiteNationaPetit.jpg?fit=354%2C266&ssl=1","_links":{"self":[{"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/posts\/1645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1645"}],"version-history":[{"count":0,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/posts\/1645\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/media\/2454"}],"wp:attachment":[{"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chsspaca.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}